{"id":5359,"date":"2022-08-18T17:59:55","date_gmt":"2022-08-18T09:59:55","guid":{"rendered":"http:\/\/loanpanda.com.my\/staging-test\/?page_id=5359"},"modified":"2023-05-25T10:46:43","modified_gmt":"2023-05-25T02:46:43","slug":"consultant","status":"publish","type":"page","link":"https:\/\/loanpanda.com.my\/test\/consultant\/","title":{"rendered":"Consultant"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row el_id=&#8221;consultant-subheader-row&#8221; css=&#8221;.vc_custom_1663394350908{margin-bottom: 50px !important;background-color: #f5f5f5 !important;}&#8221;][vc_column]        <div class=\"pageheader-second-bg \">\n        <div class=\"pageheader-second-bg-overlay\" ><\/div>\n        <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col-xl-6 col-lg-6 col-md-12 col-sm-12 col-12\">\n                    <div class=\"pageheader-second-caption\">\n                        <h1 class=\"text-white hero-slide-title\">Loan Consultant<\/h1>                                                <p>We offer 1-to-1 professional consultation to help you ensure a successful loan application\u2014with clear, uncomplicated advice to make sense of a complex financial world.<\/p>\n                                            <\/div>\n                <\/div>\n                <div class=\"col-xl-6 col-lg-6 col-md-12 col-sm-12 col-12\">\n                    <div class=\"pageheader-second-img\">\n                        <img decoding=\"async\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/consultant-banner-min.png\" alt=\"\" class=\"img-fluid\">                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    \n    [\/vc_column][\/vc_row][vc_row el_id=&#8221;consultant-content-1&#8243; css=&#8221;.vc_custom_1660812354340{margin-bottom: 70px !important;}&#8221;][vc_column width=&#8221;7\/12&#8243;][vc_column_text css=&#8221;.vc_custom_1660812627701{margin-bottom: 24px !important;}&#8221;]<\/p>\n<h2>What is LOANPANDA Mortgage Planning?<\/h2>\n<p>[\/vc_column_text][vc_column_text]Successfully securing the right loan is critical for your future. At LOANPANDA, we offer 1-to-1 online consultations that help review your credit profile and assess your loan eligibility to determine your strategic mortgage options moving forward, including recommendations on the right choice of loan package that best fits your financial situation.[\/vc_column_text][\/vc_column][vc_column width=&#8221;5\/12&#8243;][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5362\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/what-is-financial-planning-min.png\" alt=\"\" width=\"743\" height=\"495\" srcset=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/what-is-financial-planning-min.png 743w, https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/what-is-financial-planning-min-300x200.png 300w, https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/what-is-financial-planning-min-600x400.png 600w\" sizes=\"auto, (max-width: 743px) 100vw, 743px\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=&#8221;consultant-content-2&#8243; css=&#8221;.vc_custom_1664428062124{margin-right: 2rem !important;margin-bottom: 128px !important;margin-left: 2rem !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; el_id=&#8221;content-2-image-column&#8221;][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5361\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/financial.svg\" alt=\"\" width=\"366\" height=\"378\" \/>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;.vc_custom_1660812638893{margin-bottom: 8px !important;}&#8221;]<\/p>\n<h2>All-inclusive Financial Planning<\/h2>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1660812661027{margin-bottom: 24px !important;}&#8221;]<\/p>\n<h1>RM999<\/h1>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1660813445777{margin-bottom: 8px !important;}&#8221; el_id=&#8221;list-title&#8221;]Includes :[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1660813994653{margin-bottom: 32px !important;}&#8221;]<\/p>\n<ul>\n<li>A 45-minute 1-on-1 session with your dedicated planner via free online conferencing app<\/li>\n<li>In-depth analysis of your financial status<\/li>\n<li>Detailed financial goals assessment report<\/li>\n<li>Personalised execution strategy advice to guide you step by step<\/li>\n<li>6-month progress monitoring and adjustment report<\/li>\n<\/ul>\n<p>[\/vc_column_text]\n            <a class=\"btn btn-lg btn-custom btn-rounded \" href=\"https:\/\/loanpanda.com.my\/test\/cart\/?add-to-cart=3072\" style=\"background-color:#ff5959;color:#ffffff;\">Pay Now<\/a>\n    \n    [\/vc_column][\/vc_row][vc_row el_id=&#8221;consultant-content-3&#8243; css=&#8221;.vc_custom_1660815002763{margin-bottom: 130px !important;background-color: #fef6f5 !important;}&#8221;][vc_column css=&#8221;.vc_custom_1663640029614{margin-bottom: 4rem !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1660814669675{margin-top: 49px !important;margin-bottom: 48px !important;}&#8221;]<\/p>\n<h1>Financial Planner<\/h1>\n<p>[\/vc_column_text][vc_row_inner equal_height=&#8221;yes&#8221; gap=&#8221;25&#8243;][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1660899854372{padding-right: 40px !important;padding-left: 40px !important;background-color: #ffffff !important;border-radius: 15px !important;}&#8221;][vc_column_text el_class=&#8221;consultant-image&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5504\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner01.jpg\" alt=\"\" width=\"323\" height=\"323\" srcset=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner01.jpg 323w, https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner01-300x300.jpg 300w, https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner01-150x150.jpg 150w, https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner01-100x100.jpg 100w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/>[\/vc_column_text][vc_column_text el_class=&#8221;name&#8221; css=&#8221;.vc_custom_1660898741490{margin-bottom: 8px !important;}&#8221;]NG TECK KEN[\/vc_column_text][vc_column_text el_class=&#8221;job-title&#8221; css=&#8221;.vc_custom_1660898757140{margin-bottom: 23px !important;}&#8221;]Mortgage Training Manager[\/vc_column_text][vc_column_text]<\/p>\n<ul>\n<li>10 Years of Loan Consultant<\/li>\n<li>Over Thousand Acceptance Service Record &amp; Annualize Sub-Sale Acceptance over RM80 Million<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1660899859951{padding-right: 40px !important;padding-left: 40px !important;background-color: #ffffff !important;border-radius: 15px !important;}&#8221;][vc_column_text el_class=&#8221;consultant-image&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5505\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner02.jpg\" alt=\"\" width=\"323\" height=\"323\" srcset=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner02.jpg 323w, https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner02-300x300.jpg 300w, https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner02-150x150.jpg 150w, https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/Financial-Planner02-100x100.jpg 100w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/>[\/vc_column_text][vc_column_text el_class=&#8221;name&#8221; css=&#8221;.vc_custom_1660898761954{margin-bottom: 8px !important;}&#8221;]LEE JUN HOU[\/vc_column_text][vc_column_text el_class=&#8221;job-title&#8221; css=&#8221;.vc_custom_1660898767199{margin-bottom: 23px !important;}&#8221;]Senior Mortgage Consultant[\/vc_column_text][vc_column_text]<\/p>\n<ul>\n<li>4 years in Banking &amp; Finance Industry<\/li>\n<li>Mortgage Author and UCSI mortgage course Lecture<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_id=&#8221;consultant-content-4&#8243; css=&#8221;.vc_custom_1660815088248{margin-bottom: 130px !important;}&#8221;][vc_column width=&#8221;5\/12&#8243; el_id=&#8221;content-4-image-column&#8221;][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5363\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/what-you-get.svg\" alt=\"\" width=\"413\" height=\"310\" \/>[\/vc_column_text][\/vc_column][vc_column width=&#8221;7\/12&#8243;][vc_column_text css=&#8221;.vc_custom_1660815160867{margin-bottom: 24px !important;}&#8221;]<\/p>\n<h2>What You Get From Each Consultation<\/h2>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1660815172399{margin-bottom: 24px !important;}&#8221;]Each consultation is designed to maximise our service value to you, and includes a comprehensive itinerary that outlines a clear, unambiguous plan structure:[\/vc_column_text][vc_column_text]<\/p>\n<ol>\n<li>Personalised financial plan<\/li>\n<li>A detailed 3-8 page financial report<\/li>\n<li>Expert advice and recommendations<\/li>\n<li>Financial plan execution guide<\/li>\n<\/ol>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_section el_id=&#8221;consultant-content-5&#8243; css=&#8221;.vc_custom_1660816169486{margin-bottom: 158px !important;padding-top: 56px !important;padding-bottom: 113px !important;background-color: #fef6f5 !important;}&#8221;][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1660816163705{margin-bottom: 45px !important;}&#8221;]<\/p>\n<h1>Why Choose Us?<\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row gap=&#8221;25&#8243; css=&#8221;.vc_custom_1664359000574{margin-bottom: 24px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1660816227133{margin-bottom: 24px !important;}&#8221;][vc_row_inner css=&#8221;.vc_custom_1660878340696{background-color: #ffffff !important;border-radius: 15px !important;}&#8221; el_class=&#8221;content-box&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5367\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/why-choose-us.svg\" alt=\"\" width=\"56\" height=\"56\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text css=&#8221;.vc_custom_1660816276412{margin-bottom: 8px !important;}&#8221; el_id=&#8221;box-title&#8221;]Friendly, Dedicated Services[\/vc_column_text][vc_column_text]Our loan consultants are eager to help you ease your loan processing with a smile. We believe that approaching life with candid honesty is necessary to build a genuine understanding of the needs of our customers.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner css=&#8221;.vc_custom_1660878345223{background-color: #ffffff !important;border-radius: 15px !important;}&#8221; el_class=&#8221;content-box&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5364\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/why-choose-us-1.svg\" alt=\"\" width=\"56\" height=\"56\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text css=&#8221;.vc_custom_1660816281779{margin-bottom: 8px !important;}&#8221; el_id=&#8221;box-title&#8221;]Clear, Easy-to-Understand Advice[\/vc_column_text][vc_column_text]We are trusted professionals who help our customers navigate complex financial matters and legalities while providing unbiased, uncomplicated advice to help them make better decisions.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row gap=&#8221;25&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1660816234654{margin-bottom: 24px !important;}&#8221;][vc_row_inner css=&#8221;.vc_custom_1660878357433{background-color: #ffffff !important;border-radius: 15px !important;}&#8221; el_class=&#8221;content-box&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5365\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/why-choose-us-2.svg\" alt=\"\" width=\"56\" height=\"56\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text css=&#8221;.vc_custom_1660816286658{margin-bottom: 8px !important;}&#8221; el_id=&#8221;box-title&#8221;]100% Online Convenience &amp; Safety[\/vc_column_text][vc_column_text]Cut back on travel time and expenses as we conduct our consultations via a free online video-conferencing app for your convenience and safety.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner css=&#8221;.vc_custom_1660878353858{background-color: #ffffff !important;border-radius: 15px !important;}&#8221; el_class=&#8221;content-box&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5366\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/08\/why-choose-us-3.svg\" alt=\"\" width=\"56\" height=\"56\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text css=&#8221;.vc_custom_1660816291443{margin-bottom: 8px !important;}&#8221; el_id=&#8221;box-title&#8221;]Guaranteed Best Prices[\/vc_column_text][vc_column_text]We strive to offer better than market prices for professional services that make life-changing financial advice more accessible to those who need them most.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_row el_id=&#8221;faq-section&#8221; css=&#8221;.vc_custom_1663641210666{margin-bottom: 4rem !important;}&#8221;][vc_column css=&#8221;.vc_custom_1658914985008{margin-bottom: 142px !important;}&#8221;][vc_column_text]<\/p>\n<h2>FAQ<\/h2>\n<p>[\/vc_column_text]        <div class=\"accrodion-regular \">\n        <div id=\"accordion1-267602\">\n                    <div class=\"accrodion-block\">\n                <div class=\"accordion-head active\" id=\"heading-1-267602\">\n                    <h5 class=\"accordion-title\">\n                        <a href=\"#collapse-1-267602\" class=\"text-dark\" data-toggle=\"collapse\" data-target=\"#collapse-1-267602\" aria-expanded=\"true\" aria-controls=\"collapse-1-267602\">\n                            <span class=\"fa fa-fw fa-plus-circle \"><\/span>Is this an online or face-to-face service?                         <\/a>\n                    <\/h5>\n                <\/div>\n                <div id=\"collapse-1-267602\" class=\"collapse \" aria-labelledby=\"heading-1-267602\" data-parent=\"#accordion1-267602\">\n                    <div class=\"accordion-content\">\n                        This service is provided online in 45 minute sessions. Users are required to download the Zoom application to facilitate this service.                     <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"accrodion-block\">\n                <div class=\"accordion-head \" id=\"heading-2-267602\">\n                    <h5 class=\"accordion-title\">\n                        <a href=\"#collapse-2-267602\" class=\"text-dark\" data-toggle=\"collapse\" data-target=\"#collapse-2-267602\" aria-expanded=\"true\" aria-controls=\"collapse-2-267602\">\n                            <span class=\"fa fa-fw fa-plus-circle \"><\/span>How would I know if my appointment has been booked successfully?                        <\/a>\n                    <\/h5>\n                <\/div>\n                <div id=\"collapse-2-267602\" class=\"collapse \" aria-labelledby=\"heading-2-267602\" data-parent=\"#accordion1-267602\">\n                    <div class=\"accordion-content\">\n                        Our operations team will call to confirm a successful appointment after running you through a standard Know-Your-Customer background check. The system will then send out a confirmation email with detailed instructions & Zoom link to begin the consultation.                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"accrodion-block\">\n                <div class=\"accordion-head \" id=\"heading-3-267602\">\n                    <h5 class=\"accordion-title\">\n                        <a href=\"#collapse-3-267602\" class=\"text-dark\" data-toggle=\"collapse\" data-target=\"#collapse-3-267602\" aria-expanded=\"true\" aria-controls=\"collapse-3-267602\">\n                            <span class=\"fa fa-fw fa-plus-circle \"><\/span>Are there any prior preparations I should make to get the most from the service?                         <\/a>\n                    <\/h5>\n                <\/div>\n                <div id=\"collapse-3-267602\" class=\"collapse \" aria-labelledby=\"heading-3-267602\" data-parent=\"#accordion1-267602\">\n                    <div class=\"accordion-content\">\n                        Once payment is successful, you are required to sign a consent form that gives us your express permission to perform a check on your credit score that will help our financial planners better tailor the session for your benefit.                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"accrodion-block\">\n                <div class=\"accordion-head \" id=\"heading-4-267602\">\n                    <h5 class=\"accordion-title\">\n                        <a href=\"#collapse-4-267602\" class=\"text-dark\" data-toggle=\"collapse\" data-target=\"#collapse-4-267602\" aria-expanded=\"true\" aria-controls=\"collapse-4-267602\">\n                            <span class=\"fa fa-fw fa-plus-circle \"><\/span> Can I get a refund?                         <\/a>\n                    <\/h5>\n                <\/div>\n                <div id=\"collapse-4-267602\" class=\"collapse \" aria-labelledby=\"heading-4-267602\" data-parent=\"#accordion1-267602\">\n                    <div class=\"accordion-content\">\n                        You may file for a refund via email or WhatsApp 24 hours before the appointment time. If the refund request is successful, LOANPANDA will issue a refund of the amount, after deduction of administrative or service fees charged by third-party vendor(s).                     <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"accrodion-block\">\n                <div class=\"accordion-head \" id=\"heading-5-267602\">\n                    <h5 class=\"accordion-title\">\n                        <a href=\"#collapse-5-267602\" class=\"text-dark\" data-toggle=\"collapse\" data-target=\"#collapse-5-267602\" aria-expanded=\"true\" aria-controls=\"collapse-5-267602\">\n                            <span class=\"fa fa-fw fa-plus-circle \"><\/span>What will I take away from the service?                         <\/a>\n                    <\/h5>\n                <\/div>\n                <div id=\"collapse-5-267602\" class=\"collapse \" aria-labelledby=\"heading-5-267602\" data-parent=\"#accordion1-267602\">\n                    <div class=\"accordion-content\">\n                        You will gain important insights into your current financial situation, learn ways to improve it, and receive a full report all within the 45-minute consultation.                     <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"accrodion-block\">\n                <div class=\"accordion-head \" id=\"heading-6-267602\">\n                    <h5 class=\"accordion-title\">\n                        <a href=\"#collapse-6-267602\" class=\"text-dark\" data-toggle=\"collapse\" data-target=\"#collapse-6-267602\" aria-expanded=\"true\" aria-controls=\"collapse-6-267602\">\n                            <span class=\"fa fa-fw fa-plus-circle \"><\/span>Can I request that my financial consultant provide further assistance with financial issues or planning?                         <\/a>\n                    <\/h5>\n                <\/div>\n                <div id=\"collapse-6-267602\" class=\"collapse \" aria-labelledby=\"heading-6-267602\" data-parent=\"#accordion1-267602\">\n                    <div class=\"accordion-content\">\n                        Yes, you may proceed with further consultation with the financial consultant\/planner. Depending on your requirements, our consultants generally provide additional services at pretty reasonable and competitive fees.                     <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"accrodion-block\">\n                <div class=\"accordion-head \" id=\"heading-7-267602\">\n                    <h5 class=\"accordion-title\">\n                        <a href=\"#collapse-7-267602\" class=\"text-dark\" data-toggle=\"collapse\" data-target=\"#collapse-7-267602\" aria-expanded=\"true\" aria-controls=\"collapse-7-267602\">\n                            <span class=\"fa fa-fw fa-plus-circle \"><\/span>How can I protect my rights?                        <\/a>\n                    <\/h5>\n                <\/div>\n                <div id=\"collapse-7-267602\" class=\"collapse \" aria-labelledby=\"heading-7-267602\" data-parent=\"#accordion1-267602\">\n                    <div class=\"accordion-content\">\n                        If you are dissatisfied with our service, you may call our LOANPANDA customer service, email admin@loanpanda.com.my, or whatsapp your request to 6011 \u2013 5508 9898 for assistance. We will open a file to investigate the 45-min consultation service to determine the source of your grievance and take appropriate action.                    <\/div>\n                <\/div>\n            <\/div>\n                <\/div>\n    <\/div>\n    \n    [\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1658196425957{background-color: #f5f5f5 !important;}&#8221;][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1662354133900{background-color: #f5f5f5 !important;}&#8221;][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;6\/12&#8243; css=&#8221;.vc_custom_1658198808293{margin-top: 86px !important;margin-bottom: 86px !important;}&#8221; el_id=&#8221;footer-on-top&#8221;][vc_column_text css=&#8221;.vc_custom_1663400130590{margin-bottom: 8px !important;}&#8221;]<\/p>\n<h1 class=\"font-purple-primary\">We Are Here to Help<\/h1>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1663400216839{margin-bottom: 24px !important;}&#8221; el_id=&#8221;footer-on-top-subtitle&#8221;]Our mission is to deliver reliable, up-to-date tips &amp; advice[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1684982793824{margin-bottom: 8px !important;}&#8221; el_id=&#8221;footer-on-top-contact-info&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4075\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/07\/phone-dark.png\" alt=\"\" width=\"16\" height=\"16\" \/> 011-70744194[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1661765868059{margin-bottom: 36px !important;}&#8221; el_id=&#8221;footer-on-top-contact-info&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4074\" src=\"https:\/\/loanpanda.com.my\/test\/wp-content\/uploads\/2022\/07\/email-dark.png\" alt=\"\" width=\"16\" height=\"16\" \/> official@loanpanda.com.my<\/p>\n<div class=\"wpb_column vc_column_container vc_col-sm-4\">\n<div class=\"vc_column-inner vc_custom_1658194870021\">\n<div class=\"wpb_wrapper\">\n<div id=\"footer-top-right-img\" class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner el_id=&#8221;footer-on-top-btn-left&#8221; css=&#8221;.vc_custom_1663400583680{margin-bottom: 16px !important;padding-left: 0px !important;}&#8221;]\n            <a class=\"btn  btn-custom btn-rounded \" href=\"https:\/\/loanpanda.com.my\/test\/consultant\" style=\"background-color:#ff5959;color:#ffffff;\">Meet The Consultant<\/a>\n    \n    [\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;4\/12&#8243; el_id=&#8221;footer-on-top-img&#8221; offset=&#8221;vc_hidden-xs&#8221;][vc_single_image image=&#8221;4634&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_id=&#8221;consultant-subheader-row&#8221; css=&#8221;.vc_custom_1663394350908{margin-bottom: 50px !important;background-color: #f5f5f5 !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row el_id=&#8221;consultant-content-1&#8243; css=&#8221;.vc_custom_1660812354340{margin-bottom: 70px !important;}&#8221;][vc_column width=&#8221;7\/12&#8243;][vc_column_text css=&#8221;.vc_custom_1660812627701{margin-bottom: 24px !important;}&#8221;] What is LOANPANDA Mortgage Planning? [\/vc_column_text][vc_column_text]Successfully securing the right loan is critical for your future. At LOANPANDA, we offer 1-to-1 online consultations that help review your credit profile and assess your loan eligibility to determine your strategic mortgage options moving [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-5359","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/loanpanda.com.my\/test\/wp-json\/wp\/v2\/pages\/5359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loanpanda.com.my\/test\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/loanpanda.com.my\/test\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/loanpanda.com.my\/test\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/loanpanda.com.my\/test\/wp-json\/wp\/v2\/comments?post=5359"}],"version-history":[{"count":62,"href":"https:\/\/loanpanda.com.my\/test\/wp-json\/wp\/v2\/pages\/5359\/revisions"}],"predecessor-version":[{"id":14924,"href":"https:\/\/loanpanda.com.my\/test\/wp-json\/wp\/v2\/pages\/5359\/revisions\/14924"}],"wp:attachment":[{"href":"https:\/\/loanpanda.com.my\/test\/wp-json\/wp\/v2\/media?parent=5359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}